{"id":19542,"date":"2024-09-06T00:00:31","date_gmt":"2024-09-05T22:00:31","guid":{"rendered":"https:\/\/solo-musica.de\/?p=19542"},"modified":"2026-07-08T15:16:52","modified_gmt":"2026-07-08T13:16:52","slug":"hansjoerg-schellenberger-georg-philipp-telemann","status":"publish","type":"post","link":"https:\/\/solo-musica.de\/en\/hansjoerg-schellenberger-georg-philipp-telemann\/","title":{"rendered":"Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19547 size-medium\" src=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" border=\"1px solid black\" srcset=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-300x300.jpg 300w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-150x150.jpg 150w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-768x768.jpg 768w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-1536x1536.jpg 1536w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-2048x2048.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2><a href=\"https:\/\/solo-musica.de\/hansjoerg-schellenberger\/\">Hansj\u00f6rg Schellenberger<\/a><br \/>\n<span style=\"color: #c10a27;\">Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo<\/span><br \/>\nKatalog Nr.: C130229<br \/>\nVer\u00f6ffentlichung: 06.09.2024<\/h2>\n<p><a href=\"https:\/\/shop.solo-musica.de\/produkt\/hansjoerg-schellenberger-georg-philipp-telemann-zwoelf-neue-fantasien-fuer-oboe-solo\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12673 size-full\" style=\"margin-top: 10px;\" src=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2021\/03\/shop-50.png\" alt=\"\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<div style=\"clear: both;\">\n<hr \/>\n<h3>Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo<\/h3>\n<p><span style=\"font-weight: 400;\">Georg Philipp Telemann ist in die Musikgeschichte eingegangen als h\u00f6chst produktiver, systematisch arbeitender Komponist, der nicht nur was die reine Anzahl der von ihm geschriebenen Werke betrifft quasi alle anderen Komponisten seiner Zeit \u00fcbertroffen hat, sondern dar\u00fcber hinaus vielf\u00e4ltige Aufgaben in hohen musikalischen \u00c4mtern in Orten wie Leipzig, Frankfurt und die letzten 40 Jahre seines Lebens in Hamburg \u00fcbernommen hatte. In den Jahren 1732\/33 bzw. 1735 schrieb er 4 Werkgruppen von je 12 Fantasien f\u00fcr Fl\u00f6te, Violine, Cembalo und Viola da gamba &#8211; alle solo ohne basso continuo oder andere begleitende Instrumente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Da Telemann viele Instrumente selbst spielte und es durchaus in seiner Zeit \u00fcblich war, die jeweiligen Kompositionen auf verschiedenen Instrumenten zu spielen (was man besonders deutlich in der franz\u00f6sischen Barockmusik erkennen kann, der Telemann sehr zugeneigt war), ist es sehr gut nachzuvollziehen, dass die Fl\u00f6tistin Leona R\u00f6tzsch f\u00fcr einen Verlag eine Transkription f\u00fcr Fl\u00f6te anfertigte. Angeregt von dieser Transkription, die sich aber f\u00fcr die Oboe als im Allgemeinen zu hoch liegend erweist, hat in der vorliegenden Aufnahme Hansj\u00f6rg Schellenberger eine eigene Umsetzung der Fantasien in den jeweiligen Originaltonarten vorgenommen. Ebenso hat er nach bestm\u00f6glichem musikalischen Gewissen und Verst\u00e4ndnis f\u00fcr die Originalwerke versucht, dem urspr\u00fcnglichen Text so nahe wie m\u00f6glich zu bleiben, wobei nat\u00fcrlich viele Entscheidungen zu f\u00e4llen waren, welche der jeweiligen Stimmen im entsprechenden Augenblick wichtiger erschienen und herausgehoben werden sollten, welche Stimmen jeweils dann vernachl\u00e4ssigt wurden. Das ist nat\u00fcrlich eine sehr subjektive Arbeit, die zweifellos von jedem Oboisten anders betrachtet werden kann. In jedem Fall bleibt aber die Tatsache, dass diese Kompositionen von Telemann von ganz aussergew\u00f6hnlicher kompositorischer Qualit\u00e4t sind und eine ziemlich hohe Herausforderung &#8211; besonders bez\u00fcglich der Atemtechnik &#8211; an den aus\u00fcbenden Musiker stellen.<\/span><\/p>\n<hr \/>\n<\/div>\n<h2>Backcover &amp; Playlist<\/h2>\n<div style=\"clear: both;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-19548\" src=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-2100x2100.jpg\" alt=\"\" width=\"600\" height=\"600\" vspace=\"20\" srcset=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-2100x2100.jpg 2100w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-300x300.jpg 300w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-150x150.jpg 150w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-768x768.jpg 768w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-1536x1536.jpg 1536w, https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Backcover-2048x2048.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><iframe style=\"width: 500px; max-width: 660px; overflow: hidden; border-radius: 10px;\" src=\"https:\/\/embed.music.apple.com\/de\/album\/telemann-12-fantaisies-twv-40-26-37-arr-for-oboe-by\/1768042964\" height=\"600\" frameborder=\"0\" sandbox=\"allow-forms allow-popups allow-same-origin allow-scripts allow-storage-access-by-user-activation allow-top-navigation-by-user-activation\"><\/iframe><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hansj\u00f6rg Schellenberger Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo Katalog Nr.: C130229 Ver\u00f6ffentlichung: 06.09.2024 Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo Georg Philipp Telemann ist in die Musikgeschichte eingegangen als h\u00f6chst produktiver, systematisch arbeitender Komponist, der nicht nur was die reine Anzahl der von ihm geschriebenen Werke betrifft [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,3,4],"tags":[],"class_list":["post-19542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-36","category-campanella","category-schellenberger"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T22:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T13:16:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solo Musica GmbH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solo Musica GmbH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/\"},\"author\":{\"name\":\"Solo Musica GmbH\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#\\\/schema\\\/person\\\/acacb6ededb09e2bdd736bb8455222ac\"},\"headline\":\"Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo\",\"datePublished\":\"2024-09-05T22:00:31+00:00\",\"dateModified\":\"2026-07-08T13:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/4032608130229_Frontcover_Physical-scaled.jpg\",\"articleSection\":[\"2021\",\"Campanella\",\"Schellenberger\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/\",\"url\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/\",\"name\":\"Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/4032608130229_Frontcover_Physical-scaled.jpg\",\"datePublished\":\"2024-09-05T22:00:31+00:00\",\"dateModified\":\"2026-07-08T13:16:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/4032608130229_Frontcover_Physical-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/4032608130229_Frontcover_Physical-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/hansjoerg-schellenberger-georg-philipp-telemann\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/solo-musica.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#website\",\"url\":\"https:\\\/\\\/solo-musica.de\\\/\",\"name\":\"Deutsch\",\"description\":\"ARTIST FIRST!\",\"publisher\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solo-musica.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#organization\",\"name\":\"Deutsch\",\"url\":\"https:\\\/\\\/solo-musica.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-180.png\",\"contentUrl\":\"https:\\\/\\\/solo-musica.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-180.png\",\"width\":180,\"height\":180,\"caption\":\"Deutsch\"},\"image\":{\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solo-musica.de\\\/#\\\/schema\\\/person\\\/acacb6ededb09e2bdd736bb8455222ac\",\"name\":\"Solo Musica GmbH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/","og_locale":"en_US","og_type":"article","og_title":"Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch","og_url":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/","og_site_name":"Deutsch","article_published_time":"2024-09-05T22:00:31+00:00","article_modified_time":"2026-07-08T13:16:52+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg","type":"image\/jpeg"}],"author":"Solo Musica GmbH","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Solo Musica GmbH","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#article","isPartOf":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/"},"author":{"name":"Solo Musica GmbH","@id":"https:\/\/solo-musica.de\/#\/schema\/person\/acacb6ededb09e2bdd736bb8455222ac"},"headline":"Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo","datePublished":"2024-09-05T22:00:31+00:00","dateModified":"2026-07-08T13:16:52+00:00","mainEntityOfPage":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/"},"wordCount":353,"publisher":{"@id":"https:\/\/solo-musica.de\/#organization"},"image":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#primaryimage"},"thumbnailUrl":"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg","articleSection":["2021","Campanella","Schellenberger"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/","url":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/","name":"Hansj\u00f6rg Schellenberger - Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo - Deutsch","isPartOf":{"@id":"https:\/\/solo-musica.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#primaryimage"},"image":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#primaryimage"},"thumbnailUrl":"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg","datePublished":"2024-09-05T22:00:31+00:00","dateModified":"2026-07-08T13:16:52+00:00","breadcrumb":{"@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#primaryimage","url":"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg","contentUrl":"https:\/\/solo-musica.de\/wp-content\/uploads\/2024\/09\/4032608130229_Frontcover_Physical-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/solo-musica.de\/hansjoerg-schellenberger-georg-philipp-telemann\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/solo-musica.de\/"},{"@type":"ListItem","position":2,"name":"Hansj\u00f6rg Schellenberger &#8211; Georg Philipp Telemann. Zw\u00f6lf neue Fantasien f\u00fcr Oboe solo"}]},{"@type":"WebSite","@id":"https:\/\/solo-musica.de\/#website","url":"https:\/\/solo-musica.de\/","name":"Deutsch","description":"ARTIST FIRST!","publisher":{"@id":"https:\/\/solo-musica.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solo-musica.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solo-musica.de\/#organization","name":"Deutsch","url":"https:\/\/solo-musica.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solo-musica.de\/#\/schema\/logo\/image\/","url":"https:\/\/solo-musica.de\/wp-content\/uploads\/2020\/12\/logo-180.png","contentUrl":"https:\/\/solo-musica.de\/wp-content\/uploads\/2020\/12\/logo-180.png","width":180,"height":180,"caption":"Deutsch"},"image":{"@id":"https:\/\/solo-musica.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solo-musica.de\/#\/schema\/person\/acacb6ededb09e2bdd736bb8455222ac","name":"Solo Musica GmbH"}]}},"_links":{"self":[{"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/posts\/19542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/comments?post=19542"}],"version-history":[{"count":15,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/posts\/19542\/revisions"}],"predecessor-version":[{"id":22237,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/posts\/19542\/revisions\/22237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/media\/19547"}],"wp:attachment":[{"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/media?parent=19542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/categories?post=19542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solo-musica.de\/en\/wp-json\/wp\/v2\/tags?post=19542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}